{"id":4128,"date":"2020-02-15T19:47:27","date_gmt":"2020-02-15T17:47:27","guid":{"rendered":"http:\/\/archers-longwy.fr\/wordpress\/?p=4128"},"modified":"2020-11-09T16:36:39","modified_gmt":"2020-11-09T14:36:39","slug":"passage-trimestriel-des-fleches-de-progression","status":"publish","type":"post","link":"https:\/\/archers-haucourt.fr\/wordpress\/passage-trimestriel-des-fleches-de-progression\/","title":{"rendered":"Passage trimestriel des fl\u00e8ches de progression"},"content":{"rendered":"\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/archers-longwy.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155451-1024x471.jpg\" alt=\"\" class=\"wp-image-4129\" width=\"529\" height=\"242\" srcset=\"https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155451-1024x471.jpg 1024w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155451-300x138.jpg 300w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/archers-longwy.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155359-1024x471.jpg\" alt=\"\" class=\"wp-image-4131\" width=\"521\" height=\"239\" srcset=\"https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155359-1024x471.jpg 1024w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155359-300x138.jpg 300w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155359-768x354.jpg 768w\" sizes=\"auto, (max-width: 521px) 100vw, 521px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/archers-longwy.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155914-1024x471.jpg\" alt=\"\" class=\"wp-image-4132\" width=\"522\" height=\"240\" srcset=\"https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155914-1024x471.jpg 1024w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155914-300x138.jpg 300w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/IMG20200215155914-768x354.jpg 768w\" sizes=\"auto, (max-width: 522px) 100vw, 522px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Beaucoup de candidats \u00e0 l&#8217;\u00e9cole de tir et autant de r\u00e9sultats : <\/p>\n\n\n\n<p>Fl\u00e8che jaune 30 m : Nicolas 313 ; Miguel 287 ; J\u00e9r\u00f4me 282 <\/p>\n\n\n\n<p> Fl\u00e8che rouge 25 m : \u00c9milie 297<\/p>\n\n\n\n<p>Fl\u00e8che Bleue 20 m : Cl\u00e9ment 310<\/p>\n\n\n\n<p>Fl\u00e8che noire 15 m : Nabil 311, Camille 298, Jarod 281<\/p>\n\n\n\n<p>Fl\u00e8che Blanche 10 m : Pierrick 281<\/p>\n\n\n\n<p>Un rappel les fl\u00e8ches sont difficiles et pr\u00e9vues pour des adolescents et adultes minimum 280 sur 360 points soit une moyenne de 23.33 donc il faudrait 24 points \u00e0 chaque vol\u00e9e de 3 fl\u00e8ches, les enfants participent et voient leur progression de trimestre en trimestre, ils sont not\u00e9s et en g\u00e9n\u00e9ral tr\u00e8s proches du r\u00e9sultat, ils devraient y parvenir en fin d&#8217;ann\u00e9e&#8230;.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/archers-longwy.fr\/wordpress\/wp-content\/uploads\/2020\/02\/fl\u00e8ches-de-progression-1.xls\">fl\u00e8ches-de-progression-1<\/a><a href=\"http:\/\/archers-longwy.fr\/wordpress\/wp-content\/uploads\/2020\/02\/fl\u00e8ches-de-progression-1.xls\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"716\" src=\"http:\/\/archers-longwy.fr\/wordpress\/wp-content\/uploads\/2020\/02\/tableau-fl\u00e8ches-15-02-2020-1-1024x716.jpg\" alt=\"\" class=\"wp-image-4144\" srcset=\"https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/tableau-fl\u00e8ches-15-02-2020-1-1024x716.jpg 1024w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/tableau-fl\u00e8ches-15-02-2020-1-300x210.jpg 300w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/tableau-fl\u00e8ches-15-02-2020-1-768x537.jpg 768w, https:\/\/archers-haucourt.fr\/wordpress\/wp-content\/uploads\/2020\/02\/tableau-fl\u00e8ches-15-02-2020-1.jpg 1061w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>au 15\/02\/2020 <br \/><\/figcaption><\/figure>\n\n\n\n<p><a rel=\"noreferrer noopener\" aria-label=\"Accueil (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/archers-longwy.fr\/wordpress\/\" target=\"_blank\">Accueil<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beaucoup de candidats \u00e0 l&#8217;\u00e9cole de tir et autant de r\u00e9sultats : Fl\u00e8che jaune 30 m : Nicolas 313 ; Miguel 287 ; J\u00e9r\u00f4me 282 Fl\u00e8che rouge 25 m : \u00c9milie 297 Fl\u00e8che Bleue 20 m : Cl\u00e9ment 310 Fl\u00e8che noire 15 m : Nabil 311, Camille 298, Jarod 281 Fl\u00e8che Blanche 10 m : [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4128","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=4128"}],"version-history":[{"count":9,"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4128\/revisions"}],"predecessor-version":[{"id":4419,"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/posts\/4128\/revisions\/4419"}],"wp:attachment":[{"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=4128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=4128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archers-haucourt.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=4128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}